{"id":20984,"date":"2024-09-13T15:03:31","date_gmt":"2024-09-13T15:03:31","guid":{"rendered":"https:\/\/integrass.ca\/apprentissage-en-ligne\/"},"modified":"2025-02-26T08:44:30","modified_gmt":"2025-02-26T08:44:30","slug":"apprentissage-en-ligne","status":"publish","type":"page","link":"https:\/\/integrass.ca\/fr\/apprentissage-en-ligne\/","title":{"rendered":"Apprentissage en ligne"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"20984\" class=\"elementor elementor-20984 elementor-1600\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dcf77d8 e-con-full e-flex e-con e-parent\" data-id=\"dcf77d8\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-72fd228 e-flex e-con-boxed e-con e-child\" data-id=\"72fd228\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c7ba27c e-con-full e-flex e-con e-child\" data-id=\"c7ba27c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22425e0 elementor-widget elementor-widget-heading\" data-id=\"22425e0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Services de d\u00e9veloppement de logiciels eLearning et de LMS \n<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3255b7 elementor-widget elementor-widget-text-editor\" data-id=\"b3255b7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDepuis 2011, Integrass est \u00e0 l&rsquo;avant-garde du d\u00e9veloppement de solutions eLearning qui am\u00e9liorent l&rsquo;apprentissage en entreprise et offrent des retours mesurables sur le capital humain.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d9d3eb elementor-widget elementor-widget-text-editor\" data-id=\"1d9d3eb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Notre \u00e9quipe est \u00e9quip\u00e9e pour \u00e9lever votre apprentissage d&rsquo;entreprise avec une technologie innovante ou pour mettre \u00e0 jour vos syst\u00e8mes eLearning existants.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34cb084 elementor-widget elementor-widget-button\" data-id=\"34cb084\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/integrass.ca\/fr\/consultation\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Demande de service<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-34f2f9e e-con-full e-flex e-con e-child\" data-id=\"34f2f9e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d48385b elementor-widget elementor-widget-image\" data-id=\"d48385b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"548\" height=\"651\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Group-4-10.webp\" class=\"attachment-full size-full wp-image-1603\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Group-4-10.webp 548w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Group-4-10-253x300.webp 253w\" sizes=\"(max-width: 548px) 100vw, 548px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b03deaf e-con-full e-flex e-con e-parent\" data-id=\"b03deaf\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1ab17e6 e-flex e-con-boxed e-con e-child\" data-id=\"1ab17e6\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3551b4a e-con-full e-flex e-con e-child\" data-id=\"3551b4a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8478bfe elementor-widget elementor-widget-image\" data-id=\"8478bfe\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"610\" height=\"412\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Rectangle-7048.webp\" class=\"attachment-large size-large wp-image-1606\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Rectangle-7048.webp 610w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Rectangle-7048-300x203.webp 300w\" sizes=\"(max-width: 610px) 100vw, 610px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a7f0d34 e-con-full e-flex e-con e-child\" data-id=\"a7f0d34\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ffeeb2 elementor-widget elementor-widget-image-box\" data-id=\"1ffeeb2\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Objectif du d\u00e9veloppement de l'eLearning <br><\/h3><p class=\"elementor-image-box-description\">Nos services de d\u00e9veloppement eLearning visent \u00e0 cr\u00e9er des outils puissants tels que les syst\u00e8mes de gestion de l'apprentissage (LMS), les syst\u00e8mes de gestion des contenus d'apprentissage (LCMS) et les plateformes d'exp\u00e9rience d'apprentissage (LXP). Ces outils aident les organisations \u00e0 am\u00e9liorer l'efficacit\u00e9 de l'apprentissage et \u00e0 r\u00e9duire les co\u00fbts de formation. \n<br><br>Notre d\u00e9veloppement complet de logiciels eLearning comprend le conseil, la conception, le codage, la modernisation des syst\u00e8mes existants, ainsi que la personnalisation et l'int\u00e9gration des plates-formes eLearning existantes.\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ce4da9a e-con-full e-flex e-con e-parent\" data-id=\"ce4da9a\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f45b784 e-flex e-con-boxed e-con e-child\" data-id=\"f45b784\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-33d6fa1 elementor-widget elementor-widget-heading\" data-id=\"33d6fa1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Types de solutions eLearning que nous proposons<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5aa165f e-con-full e-flex e-con e-child\" data-id=\"5aa165f\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-cb47940 e-con-full e-flex e-con e-child\" data-id=\"cb47940\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13f3dd0 elementor-position-top elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"13f3dd0\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/integrass.ca\/fr\/soins-de-sante\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"80\" height=\"80\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Frame-e7.webp\" class=\"attachment-full size-full wp-image-1613\" alt=\"\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/integrass.ca\/fr\/soins-de-sante\/\">Gestion de l'apprentissage en ligne Syst\u00e8mes<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-930f4a9 e-con-full e-flex e-con e-child\" data-id=\"930f4a9\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d97871 elementor-position-top elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"0d97871\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"80\" height=\"81\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Frame-e2.webp\" class=\"attachment-full size-full wp-image-1616\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Plateformes eLearning<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5359bd9 e-con-full e-flex e-con e-child\" data-id=\"5359bd9\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea29316 elementor-position-top elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"ea29316\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"80\" height=\"80\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Frame-e3.webp\" class=\"attachment-full size-full wp-image-1617\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Apprentissage par l'exp\u00e9rience <br><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-635331b e-con-full e-flex e-con e-child\" data-id=\"635331b\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e39390 elementor-position-top elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"0e39390\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"80\" height=\"80\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Frame-e4.webp\" class=\"attachment-full size-full wp-image-1618\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Proctorat d'examen \u00e0 distance <br>Solutions<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-28ac468 e-con-full e-flex e-con e-child\" data-id=\"28ac468\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-669b908 e-con-full e-flex e-con e-child\" data-id=\"669b908\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9a1785a elementor-position-top elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"9a1785a\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"80\" height=\"81\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Frame-e5.webp\" class=\"attachment-full size-full wp-image-1611\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">CMS pour l'apprentissage en ligne<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6dd6c12 e-con-full e-flex e-con e-child\" data-id=\"6dd6c12\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b78e5d elementor-position-top elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1b78e5d\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"80\" height=\"80\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Frame-e6.webp\" class=\"attachment-full size-full wp-image-1612\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Mobile Learning<br> Solutions (MLS)<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ddc9195 e-con-full e-flex e-con e-child\" data-id=\"ddc9195\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8986189 elementor-position-top elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"8986189\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"80\" height=\"80\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Frame-e7.webp\" class=\"attachment-full size-full wp-image-1613\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Gestion de l'information <br>Syst\u00e8mes<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-50f41a0 e-con-full e-flex e-con e-child\" data-id=\"50f41a0\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ba4554 elementor-position-top elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"7ba4554\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"80\" height=\"80\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Frame-e8.webp\" class=\"attachment-full size-full wp-image-1614\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Logiciel de classe virtuelle<br> <\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eed96fb e-con-full e-flex e-con e-parent\" data-id=\"eed96fb\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5b7154b e-flex e-con-boxed e-con e-child\" data-id=\"5b7154b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b36dbe0 e-con-full e-flex e-con e-child\" data-id=\"b36dbe0\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-d9c98c6 e-con-full e-flex e-con e-child\" data-id=\"d9c98c6\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f97fb92 elementor-widget elementor-widget-heading\" data-id=\"f97fb92\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00e9monstration du syst\u00e8me de gestion de l'apprentissage<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-621eb68 elementor-widget elementor-widget-text-editor\" data-id=\"621eb68\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tD\u00e9couvrez comment un syst\u00e8me de gestion de l&rsquo;apprentissage peut rationaliser les activit\u00e9s d&rsquo;apprentissage en ligne, de l&rsquo;inscription aux cours \u00e0 l&rsquo;\u00e9valuation des connaissances des apprenants et \u00e0 la d\u00e9livrance de certifications.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6ab97be e-con-full e-flex e-con e-child\" data-id=\"6ab97be\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f28247f elementor-align-right elementor-widget elementor-widget-button\" data-id=\"f28247f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/integrass.ca\/contactez-nous\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ESSAYEZ LA D\u00c9MO LMS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-50b2ae8 e-con-full e-flex e-con e-parent\" data-id=\"50b2ae8\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57138b7 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"57138b7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">  Principales capacit\u00e9s des logiciels eLearning que nous d\u00e9veloppons<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d94c79d e-flex e-con-boxed e-con e-child\" data-id=\"d94c79d\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-30ca2c9 e-con-full e-flex e-con e-child\" data-id=\"30ca2c9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9d48339 elementor-widget elementor-widget-heading\" data-id=\"9d48339\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cr\u00e9ation de contenu et gestion de \n<br><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa0ae73 elementor-widget elementor-widget-text-editor\" data-id=\"aa0ae73\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><p><strong>Outils de cr\u00e9ation :<\/strong> Outils conviviaux pour cr\u00e9er un contenu de cours attrayant et interactif.<\/p><\/li><li><p><strong>Biblioth\u00e8ques de contenu :<\/strong> Acc\u00e8s \u00e0 une vaste biblioth\u00e8que de cours et de mod\u00e8les pr\u00e9construits.<\/p><\/li><li><p><strong>Contr\u00f4le de version :<\/strong> Suivez les modifications et g\u00e9rez plusieurs versions du contenu du cours.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31ea53d elementor-widget elementor-widget-heading\" data-id=\"31ea53d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Appr\u00e9ciation et \u00e9valuation<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b31b2d elementor-widget elementor-widget-text-editor\" data-id=\"6b31b2d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><p><strong>Quiz et examens :<\/strong> Cr\u00e9ez diff\u00e9rents types d&rsquo;\u00e9valuation, y compris des questions \u00e0 choix multiples, des questions \u00e0 compl\u00e9ter et des questions \u00e0 d\u00e9veloppement.<\/p><\/li><li><p><strong>Notation automatique :<\/strong> Corrigez automatiquement les quiz et les examens pour gagner du temps.<\/p><p>Rapports et<\/p><\/li><li><p><strong>Analyses :<\/strong> G\u00e9n\u00e9rez des rapports d\u00e9taill\u00e9s sur les performances des apprenants et identifiez les domaines \u00e0 am\u00e9liorer.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-37682d4 e-con-full e-flex e-con e-child\" data-id=\"37682d4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ca88bd elementor-widget elementor-widget-image\" data-id=\"7ca88bd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"518\" height=\"898\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/mobile-image.webp\" class=\"attachment-large size-large wp-image-1619\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/mobile-image.webp 518w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/mobile-image-173x300.webp 173w\" sizes=\"(max-width: 518px) 100vw, 518px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-834e2f8 e-con-full e-flex e-con e-child\" data-id=\"834e2f8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-079e7a7 elementor-widget elementor-widget-heading\" data-id=\"079e7a7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cours dispens\u00e9s et \n<br>Suivi\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf61187 elementor-widget elementor-widget-text-editor\" data-id=\"cf61187\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><p><strong>Options d&rsquo;enseignement flexibles :<\/strong> Prise en charge de diverses m\u00e9thodes d&rsquo;enseignement, y compris l&rsquo;auto-apprentissage, l&rsquo;apprentissage avec instructeur et l&rsquo;apprentissage mixte.<\/p><\/li><li><p><strong>Analyse de l&rsquo;apprenant :<\/strong> Suivez les progr\u00e8s, l&rsquo;engagement et les performances de l&rsquo;apprenant.<\/p><\/li><li><p><strong>\u00c9l\u00e9ments de gamification :<\/strong> Incorporez des \u00e9l\u00e9ments bas\u00e9s sur le jeu pour renforcer la motivation et l&rsquo;engagement de l&rsquo;apprenant.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0928f2 elementor-widget elementor-widget-heading\" data-id=\"c0928f2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Collaboration et communication<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbf573d elementor-widget elementor-widget-text-editor\" data-id=\"bbf573d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><p><strong>Forums de discussion :<\/strong> Faciliter les discussions et le partage des connaissances entre les apprenants.<\/p><\/li><li><p><strong>Messagerie et chat :<\/strong> Permettre une communication en temps r\u00e9el entre les apprenants et les formateurs.<\/p><\/li><li><p><strong>Collaboration de groupe :<\/strong> Soutenez les projets de collaboration et les travaux de groupe.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a711825 e-con-full e-flex e-con e-parent\" data-id=\"a711825\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-980a161 e-flex e-con-boxed e-con e-child\" data-id=\"980a161\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e5e119b elementor-widget elementor-widget-heading\" data-id=\"e5e119b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00c9tudes de cas e-Learning tri\u00e9es sur le volet<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7759c01 elementor-widget elementor-widget-image\" data-id=\"7759c01\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/integrass.ca\/media\/case-studies\/digital-platform-upgrade-for-a-leading-motorcycle-coaching-organization\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"889\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/Rectangle-7078-1-scaled.webp\" class=\"attachment-full size-full wp-image-16066\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/Rectangle-7078-1-scaled.webp 2560w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/Rectangle-7078-1-300x104.webp 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/Rectangle-7078-1-1024x356.webp 1024w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/Rectangle-7078-1-768x267.webp 768w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/Rectangle-7078-1-1536x533.webp 1536w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/Rectangle-7078-1-2048x711.webp 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-50a9338 e-flex e-con-boxed e-con e-child\" data-id=\"50a9338\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8ece8b5 e-con-full classbg e-flex e-con e-child\" data-id=\"8ece8b5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d9f3f6 elementor-widget elementor-widget-heading\" data-id=\"6d9f3f6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/integrass.ca\/media\/case-studies\/digital-platform-upgrade-for-a-leading-motorcycle-coaching-organization\/\">Mise \u00e0 niveau de la plateforme num\u00e9rique d'une organisation leader dans le domaine de l'entra\u00eenement des motocyclistes<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d060806 elementor-widget elementor-widget-text-editor\" data-id=\"d060806\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Migration r\u00e9ussie de tous les actifs num\u00e9riques existants et des donn\u00e9es historiques. Nous avons proc\u00e9d\u00e9 \u00e0 une \u00e9valuation approfondie et formul\u00e9 des recommandations strat\u00e9giques conformes aux meilleures pratiques.   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03f5508 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"03f5508\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/integrass.ca\/media\/case-studies\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Plus d'histoires<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bc45a1e e-con-full e-flex e-con e-parent\" data-id=\"bc45a1e\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2957c83 e-flex e-con-boxed e-con e-child\" data-id=\"2957c83\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9593f00 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"9593f00\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">  Avantages de la collaboration avec \nIntegrass<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-646562c e-con-full e-flex e-con e-child\" data-id=\"646562c\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-feec141 e-con-full e-flex e-con e-child\" data-id=\"feec141\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dbd1ce8 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"dbd1ce8\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Frame-e12.webp\" class=\"attachment-full size-full wp-image-1621\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Livraison rapide de logiciels<\/h3><p class=\"elementor-image-box-description\">En s'appuyant sur nos solides m\u00e9thodologies Agile et DevOps, Integrass peut fournir des logiciels eLearning personnalis\u00e9s de mani\u00e8re efficace et rapide.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e179218 e-con-full e-flex e-con e-child\" data-id=\"e179218\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9a08134 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"9a08134\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Frame-e13.webp\" class=\"attachment-full size-full wp-image-1622\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Une qualit\u00e9 exceptionnelle<\/h3><p class=\"elementor-image-box-description\">Nous garantissons des solutions de premier ordre gr\u00e2ce \u00e0 une conception r\u00e9fl\u00e9chie de l'application, des techniques de codage normalis\u00e9es et des tests parall\u00e8les rigoureux tout au long du processus de d\u00e9veloppement.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-51e0d05 e-con-full e-flex e-con e-child\" data-id=\"51e0d05\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f603fc elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"2f603fc\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Frame-e14.webp\" class=\"attachment-full size-full wp-image-1623\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">D\u00e9veloppement rentable<\/h3><p class=\"elementor-image-box-description\">Notre \u00e9quipe vous aide \u00e0 maximiser votre budget en recommandant l'architecture eLearning la plus efficace, en s\u00e9lectionnant une pile technologique pratique et en rassemblant une \u00e9quipe de d\u00e9veloppement adapt\u00e9e \u00e0 vos besoins.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0656a4f e-con-full e-flex e-con e-child\" data-id=\"0656a4f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7754deb elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"7754deb\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Frame-e15.webp\" class=\"attachment-full size-full wp-image-1624\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Am\u00e9lioration de l'engagement des utilisateurs<\/h3><p class=\"elementor-image-box-description\">Votre application eLearning sera dot\u00e9e de fonctionnalit\u00e9s riches, d'une interface intuitive, d'outils d'engagement avanc\u00e9s et d'une exp\u00e9rience transparente bas\u00e9e sur les r\u00f4les, ce qui favorisera l'adoption par les utilisateurs.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5219b00 e-con-full e-flex e-con e-parent\" data-id=\"5219b00\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e02fbdc e-flex e-con-boxed e-con e-child\" data-id=\"e02fbdc\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-65c8bfa e-con-full e-flex e-con e-child\" data-id=\"65c8bfa\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39f50d7 elementor-widget elementor-widget-image\" data-id=\"39f50d7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"538\" height=\"533\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/pikaso_texttoimage_Design-a-sleek-and-userfriendly-UI-for-a-successfu-5.webp\" class=\"attachment-large size-large wp-image-1625\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/pikaso_texttoimage_Design-a-sleek-and-userfriendly-UI-for-a-successfu-5.webp 538w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/pikaso_texttoimage_Design-a-sleek-and-userfriendly-UI-for-a-successfu-5-300x297.webp 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/pikaso_texttoimage_Design-a-sleek-and-userfriendly-UI-for-a-successfu-5-150x150.webp 150w\" sizes=\"(max-width: 538px) 100vw, 538px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5afb6a0 e-con-full e-flex e-con e-child\" data-id=\"5afb6a0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bab00fe elementor-widget elementor-widget-heading\" data-id=\"bab00fe\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quelle approche pour un d\u00e9veloppement r\u00e9ussi du logiciel eLearning ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3808052 elementor-widget elementor-widget-text-editor\" data-id=\"3808052\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Plus de 13 ans dans le d\u00e9veloppement de logiciels eLearning, l&rsquo;analyse de donn\u00e9es et l&rsquo;IA.<\/li><li>Plus de 10 ans d&rsquo;exp\u00e9rience dans le d\u00e9veloppement de logiciels d&rsquo;apprentissage en ligne.<\/li><li>Plus de 25 analystes commerciaux avec 5 \u00e0 9 ans d&rsquo;exp\u00e9rience.<\/li><li>Expertise dans plus de 30 secteurs d&rsquo;activit\u00e9, dont la sant\u00e9, BFSI, la vente au d\u00e9tail, l&rsquo;industrie, le p\u00e9trole et le gaz.<\/li><li>Une expertise approfondie du secteur et des r\u00e9sultats probants.<\/li><li>Une \u00e9quipe solide de professionnels exp\u00e9riment\u00e9s.<\/li><li>Une connaissance diversifi\u00e9e de l&rsquo;industrie.<\/li><li>Concentrez-vous sur les connaissances fond\u00e9es sur les donn\u00e9es.<\/li><li>Innovation et am\u00e9lioration continues.  <\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2fa43d9 e-con-full e-flex e-con e-parent\" data-id=\"2fa43d9\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-fb233f3 e-flex e-con-boxed e-con e-child\" data-id=\"fb233f3\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0980cf1 elementor-widget elementor-widget-heading\" data-id=\"0980cf1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Notre approche de la r\u00e9ussite de l'apprentissage en ligne \n<br>D\u00e9veloppement de logiciels\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a79ee38 elementor-widget elementor-widget-text-editor\" data-id=\"a79ee38\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tChez Integrass, nos \u00e9quipes de d\u00e9veloppement alignent les livrables du projet sur vos objectifs commerciaux, assurent une collaboration transparente sur\net g\u00e8rent les incertitudes avec agilit\u00e9. Cliquez ci-dessous pour d\u00e9couvrir comment nos pratiques permettent de mener \u00e0 bien des projets eLearning sur\n, en vous appuyant sur des exemples de r\u00e9alisations r\u00e9centes. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b6e6325 e-con-full e-flex e-con e-child\" data-id=\"b6e6325\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-11cd6e7 e-con-full e-flex e-con e-child\" data-id=\"11cd6e7\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2533be4 elementor-widget elementor-widget-heading\" data-id=\"2533be4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pratiques cl\u00e9s pour la r\u00e9ussite du projet eLearning \n<br><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2179419 elementor-widget elementor-widget-image-box\" data-id=\"2179419\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Port\u00e9e du projet et gestion des changements<\/h3><p class=\"elementor-image-box-description\">D\u00e9finissez clairement la port\u00e9e du projet et g\u00e9rez efficacement tout changement.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba34297 elementor-widget elementor-widget-image-box\" data-id=\"ba34297\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Optimisation et d\u00e9ploiement des ressources<\/h3><p class=\"elementor-image-box-description\">Planifier et allouer efficacement les ressources pour maximiser l'impact du projet.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52a535d elementor-widget elementor-widget-image-box\" data-id=\"52a535d\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Budg\u00e9tisation et contr\u00f4le financier<\/h3><p class=\"elementor-image-box-description\">Veiller \u00e0 une estimation pr\u00e9cise des co\u00fbts et maintenir la discipline budg\u00e9taire.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f956c01 elementor-widget elementor-widget-image-box\" data-id=\"f956c01\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Analyse et pr\u00e9vention des risques<\/h3><p class=\"elementor-image-box-description\">Identifier les risques de mani\u00e8re proactive et mettre en \u0153uvre des mesures pr\u00e9ventives.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7eee75 elementor-widget elementor-widget-image-box\" data-id=\"b7eee75\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Suivi du projet et rapports<\/h3><p class=\"elementor-image-box-description\">Suivre les performances au moyen d'indicateurs cl\u00e9s et fournir des mises \u00e0 jour coh\u00e9rentes sur le site \n.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e4bc65 elementor-widget elementor-widget-image-box\" data-id=\"5e4bc65\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Adaptation et partage des connaissances<\/h3><p class=\"elementor-image-box-description\">G\u00e9rer les demandes de changement en douceur et faciliter un transfert de connaissances efficace.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c972d0c e-con-full e-flex e-con e-child\" data-id=\"c972d0c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b3d8ef6 elementor-widget elementor-widget-image\" data-id=\"b3d8ef6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"661\" height=\"724\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/pikaso_texttoimage_Design-a-sleek-and-userfriendly-UI-for-a-successfu-4.webp\" class=\"attachment-large size-large wp-image-1626\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/pikaso_texttoimage_Design-a-sleek-and-userfriendly-UI-for-a-successfu-4.webp 661w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/pikaso_texttoimage_Design-a-sleek-and-userfriendly-UI-for-a-successfu-4-274x300.webp 274w\" sizes=\"(max-width: 661px) 100vw, 661px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8ae318b e-con-full e-flex e-con e-parent\" data-id=\"8ae318b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-5d23dcd e-flex e-con-boxed e-con e-child\" data-id=\"5d23dcd\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a440d9 elementor-widget elementor-widget-heading\" data-id=\"1a440d9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les voix de nos clients satisfaits<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5f0af6 elementor-widget elementor-widget-ucaddon_responsive_testemonial_carousel\" data-id=\"f5f0af6\" data-element_type=\"widget\" data-widget_type=\"ucaddon_responsive_testemonial_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Testimonial Carousel -->\n\t\t<link id='font-awesome-css' href='https:\/\/integrass.ca\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/integrass.ca\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-v4-shims.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='owl-carousel-css' href='https:\/\/integrass.ca\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/owl-carousel-new\/assets\/owl.carousel.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Testimonial Carousel *\/\n\n\/* general styles *\/\n.uc_quote_slider{\n  min-height:1px;\n}\n\n#uc_responsive_testemonial_carousel_elementor_f5f0af6 *{\n  box-sizing:border-box;\n}\n\n#uc_responsive_testemonial_carousel_elementor_f5f0af6 .uc_quote_info .uc_author_avatar {\n  width: 100%;\n}\n\n#uc_responsive_testemonial_carousel_elementor_f5f0af6 .uc_quote_info .uc_author {\n  display: inline-flex;\n  align-items: flex-start; \n  }\n\n#uc_responsive_testemonial_carousel_elementor_f5f0af6 .uc_stars{\n  display:flex;\n}\n\n#uc_responsive_testemonial_carousel_elementor_f5f0af6 .uc_quote_info{\n  display:flex;\n}\n\n#uc_responsive_testemonial_carousel_elementor_f5f0af6 *{\n  outline:none;\n}\n\n#uc_responsive_testemonial_carousel_elementor_f5f0af6 .ue-image{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n#uc_responsive_testemonial_carousel_elementor_f5f0af6 .uc_quote_info .uc_author_info .uc_company {\n    color: ;\n}\n\n#uc_responsive_testemonial_carousel_elementor_f5f0af6 .ue-image-spacing{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n#uc_responsive_testemonial_carousel_elementor_f5f0af6 .ue-icon{\n  display:inline-flex;\n  justify-content:center;\n  align-items:center;\n}\n\n#uc_responsive_testemonial_carousel_elementor_f5f0af6 .ue-icon svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_responsive_testemonial_carousel_elementor_f5f0af6 .uc_quote_item,\n#uc_responsive_testemonial_carousel_elementor_f5f0af6 .ue-flip-item-content{\n  transition: all .3s;\n}\n\n\/* end general styles *\/\n\n\/* carousel type owl *\/\n  #uc_responsive_testemonial_carousel_elementor_f5f0af6 .owl-dots {\n    overflow:hidden;\n  }\n\n  #uc_responsive_testemonial_carousel_elementor_f5f0af6 .owl-dot {\n    display:inline-block;\n  }\n\n  #uc_responsive_testemonial_carousel_elementor_f5f0af6 .owl-nav .owl-prev,\n  #uc_responsive_testemonial_carousel_elementor_f5f0af6 .owl-nav .owl-next{\n      position:absolute;\n      display:inline-block;\n      text-align:center;\n  }\n\n  \n  \n\n\/* end carousel type owl *\/\n\n\/* carosuel type grid *\/\n.team_member_grid{\n  position:relative;\n  display:grid;\n}\n\n.team_member_grid .ue_grid_item{\n  position:relative;\n  display:flex;\n  flex-direction:column;\n}\n\/* end carousel type grid *\/\n\n<\/style>\n\n<div class=\"uc_quote_slider\" style=\"direction:ltr\" >  \n  <!-- carousel type owl -->\n  \t<div class=\"uc_carousel owl-carousel owl-theme uc-items-wrapper  \" id=\"uc_responsive_testemonial_carousel_elementor_f5f0af6\"  >\n          \t\t<div class=\"uc_quote_item ue-item     elementor-repeater-item-88def90\">\n\t\t\t<div class=\"uc_quote_info \">\n                \n\t\t\t\t<div class=\"uc_author\">\n                  \t                    <div class=\"ue-image\">\n\t\t\t\t\t   <img loading=\"lazy\" decoding=\"async\" class=\"uc_author_avatar\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/08\/testiml.jpg-2.webp\" height=\"48\" width=\"48\" alt=\"\" \/>\n                    <\/div>\n                    <div class=\"ue-image-spacing\"><\/div>\n                                      \n\t\t\t\t\t<div class=\"uc_author_info\">\n\t\t\t\t\t\t<div class=\"ue_title\">Keith Howell<\/div>\t\t\t\t\t\t<div class=\"ue_subtitle\">Associ\u00e9 \/ cofondateur de Clear Cadence, LLC<\/div>                        \n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n                <!-- end of credentials -->\n              \n                <div class=\"ue-text\"><p>\nIntegrass est un partenaire de d\u00e9veloppement et de services professionnel et comp\u00e9tent de ClearCadence, qui fournit des solutions \u00e0 notre base de clients. Nous sommes heureux d'avoir Integrass comme partenaire strat\u00e9gique et de b\u00e9n\u00e9ficier d'une relation \u00e0 long terme. <\/p><\/div>              \n              \t\t\t\t\t              \n              \n              \n                            \n\t\t\t<\/div>\n        <\/div>\n  <!-- end of block item -->\n\t<div class=\"uc_quote_item ue-item     elementor-repeater-item-3f1b7c6\">\n\t\t\t<div class=\"uc_quote_info \">\n                \n\t\t\t\t<div class=\"uc_author\">\n                  \t                    <div class=\"ue-image\">\n\t\t\t\t\t   <img loading=\"lazy\" decoding=\"async\" class=\"uc_author_avatar\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/08\/robert.jpg-2.webp\" height=\"48\" width=\"48\" alt=\"\" \/>\n                    <\/div>\n                    <div class=\"ue-image-spacing\"><\/div>\n                                      \n\t\t\t\t\t<div class=\"uc_author_info\">\n\t\t\t\t\t\t<div class=\"ue_title\">Robert Irwine<\/div>\t\t\t\t\t\t<div class=\"ue_subtitle\">Vice-pr\u00e9sident de l'architecture chez Fiserv<\/div>                        \n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n                <!-- end of credentials -->\n              \n                <div class=\"ue-text\"><p>Integrass assure une excellente gestion des projets et des programmes dans le cadre de ses projets de livraison.\n<\/p><\/div>              \n              \t\t\t\t\t              \n              \n              \n                            \n\t\t\t<\/div>\n        <\/div>\n  <!-- end of block item -->\n\t<div class=\"uc_quote_item ue-item     elementor-repeater-item-b263ca0\">\n\t\t\t<div class=\"uc_quote_info \">\n                \n\t\t\t\t<div class=\"uc_author\">\n                  \t                    <div class=\"ue-image\">\n\t\t\t\t\t   <img loading=\"lazy\" decoding=\"async\" class=\"uc_author_avatar\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/08\/Will-Circle.jpg-2.webp\" height=\"48\" width=\"48\" alt=\"\" \/>\n                    <\/div>\n                    <div class=\"ue-image-spacing\"><\/div>\n                                      \n\t\t\t\t\t<div class=\"uc_author_info\">\n\t\t\t\t\t\t<div class=\"ue_title\">William Wellons<\/div>\t\t\t\t\t\t<div class=\"ue_subtitle\">Pr\u00e9sident de Wellons Communications<\/div>                        \n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n                <!-- end of credentials -->\n              \n                <div class=\"ue-text\"><p>Integrass est ax\u00e9 sur le service \u00e0 la client\u00e8le. L'\u00e9quipe diagnostique les besoins\net fournit des solutions personnalis\u00e9es de mani\u00e8re efficace et efficiente. <\/p><\/div>              \n              \t\t\t\t\t              \n              \n              \n                            \n\t\t\t<\/div>\n        <\/div>\n  <!-- end of block item -->\n\t<div class=\"uc_quote_item ue-item     elementor-repeater-item-2fac8d4\">\n\t\t\t<div class=\"uc_quote_info \">\n                \n\t\t\t\t<div class=\"uc_author\">\n                  \t                    <div class=\"ue-image\">\n\t\t\t\t\t   <img loading=\"lazy\" decoding=\"async\" class=\"uc_author_avatar\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/08\/usa_shooting-1.png-2.webp\" height=\"48\" width=\"48\" alt=\"\" \/>\n                    <\/div>\n                    <div class=\"ue-image-spacing\"><\/div>\n                                      \n\t\t\t\t\t<div class=\"uc_author_info\">\n\t\t\t\t\t\t<div class=\"ue_title\">Brent McPherson<\/div>\t\t\t\t\t\t<div class=\"ue_subtitle\">  Directeur des installations<\/div>                        \n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n                <!-- end of credentials -->\n              \n                <div class=\"ue-text\"><p>Integrass a visit\u00e9 le si\u00e8ge d'USA Shooting \u00e0 Colorado Springs dans le cadre de nos activit\u00e9s de mise en service de notre nouvelle plateforme de gestion des membres et des \u00e9v\u00e9nements. Partenariat et lancement r\u00e9ussis ! <\/p><\/div>              \n              \t\t\t\t\t              \n              \n              \n                            \n\t\t\t<\/div>\n        <\/div>\n  <!-- end of block item -->\n\n    <\/div>\t\t\n    <!-- end carousel type owl -->\n\n  <!-- carousel type marquee -->\n    <!-- end carousel type marquee -->\n\n  <!-- carousel type coverflow -->\n    <!-- end carousel type coverflow -->\n\n  <!-- carousel type swipe -->\n    <!-- end carousel type swipe -->\n\n  <!-- carousel type grid -->\n    <!-- end carousel type grid -->\n\n<\/div>\n<!-- end Testimonial Carousel -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-487b6ec e-con-full e-flex e-con e-parent\" data-id=\"487b6ec\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-0201ffc e-flex e-con-boxed e-con e-child\" data-id=\"0201ffc\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eeaef29 elementor-widget elementor-widget-heading\" data-id=\"eeaef29\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Choisissez votre option de service eLearning<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-60d93d7 e-con-full e-flex e-con e-child\" data-id=\"60d93d7\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5992d2b e-con-full e-flex e-con e-child\" data-id=\"5992d2b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69f032b elementor-widget elementor-widget-image\" data-id=\"69f032b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"609\" height=\"567\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Group-481750.webp\" class=\"attachment-large size-large wp-image-1627\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Group-481750.webp 609w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Group-481750-300x279.webp 300w\" sizes=\"(max-width: 609px) 100vw, 609px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-03159fd e-con-full e-flex e-con e-child\" data-id=\"03159fd\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b12f4b elementor-widget elementor-widget-heading\" data-id=\"8b12f4b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Solutions eLearning personnalis\u00e9es<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-346d45b elementor-widget elementor-widget-heading\" data-id=\"346d45b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nous proposons une gamme compl\u00e8te de services de d\u00e9veloppement eLearning personnalis\u00e9s, con\u00e7us pour r\u00e9pondre \u00e0 vos besoins sp\u00e9cifiques :<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1427711 elementor-widget elementor-widget-text-editor\" data-id=\"1427711\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>\u00c9valuation des besoins \u00e9ducatifs : Analyser et comprendre vos besoins en mati\u00e8re d&rsquo;\u00e9ducation.<\/li><li>S\u00e9lection de la solution : Identifiez la solution eLearning la plus appropri\u00e9e, qu&rsquo;il s&rsquo;agisse d&rsquo;un LMS, d&rsquo;un LXP ou d&rsquo;un portail eLearning.<\/li><li>Choix de la technologie et de la m\u00e9thodologie : s\u00e9lectionnez la meilleure pile technologique et la meilleure approche de d\u00e9veloppement.<\/li><li>D\u00e9veloppement de logiciels de bout en bout : Superviser l&rsquo;ensemble du processus de d\u00e9veloppement de votre logiciel eLearning, de la conception \u00e0 la r\u00e9alisation.<\/li><li>Int\u00e9gration des syst\u00e8mes : Assurer une int\u00e9gration harmonieuse avec les syst\u00e8mes et plateformes existants.<\/li><li>Assurance qualit\u00e9 : Effectuez des tests rigoureux afin de fournir un produit de haute qualit\u00e9.<\/li><li>Formation des utilisateurs et transfert des connaissances : Fournir une formation compl\u00e8te et un transfert de connaissances pour garantir une utilisation efficace.<\/li><li>Soutien continu : Offrez un soutien continu et des mises \u00e0 jour apr\u00e8s la mise en \u0153uvre.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64e64bc e-con-full e-flex e-con e-child\" data-id=\"64e64bc\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c664454 e-con-full e-flex e-con e-child\" data-id=\"c664454\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d337e9 elementor-widget elementor-widget-heading\" data-id=\"4d337e9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mettez \u00e0 jour votre plateforme eLearning existante \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cb02b4 elementor-widget elementor-widget-heading\" data-id=\"2cb02b4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Am\u00e9liorez la fonctionnalit\u00e9 et l'efficacit\u00e9 de votre syst\u00e8me eLearning actuel gr\u00e2ce \u00e0 nos services d'am\u00e9lioration :<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd34ab7 elementor-widget elementor-widget-text-editor\" data-id=\"dd34ab7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Optimisation des processus gr\u00e2ce aux technologies \u00e9mergentes : Identifiez et am\u00e9liorez les processus d&rsquo;apprentissage en utilisant des technologies de pointe comme l&rsquo;IA, la RV, la RA ou le big data.  <\/li><li>\u00c9laborer une analyse de rentabilit\u00e9 : Cr\u00e9ez des analyses de rentabilit\u00e9 d\u00e9taill\u00e9es comprenant les co\u00fbts, les risques, le retour sur investissement et la valeur actualis\u00e9e nette.  <\/li><li>Am\u00e9lioration des fonctionnalit\u00e9s et int\u00e9gration : D\u00e9veloppez, int\u00e9grez et testez des fonctionnalit\u00e9s avanc\u00e9es pour am\u00e9liorer votre plateforme.  <\/li><li>Formation et soutien : Facilitez l&rsquo;adoption en douceur gr\u00e2ce \u00e0 une formation et une assistance compl\u00e8tes.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a0daeff e-con-full e-flex e-con e-child\" data-id=\"a0daeff\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c2f9a20 elementor-widget elementor-widget-image\" data-id=\"c2f9a20\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"609\" height=\"567\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Group-481749.webp\" class=\"attachment-large size-large wp-image-1628\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Group-481749.webp 609w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Group-481749-300x279.webp 300w\" sizes=\"(max-width: 609px) 100vw, 609px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a16c5de e-con-full e-flex e-con e-child\" data-id=\"a16c5de\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a687ab9 e-con-full e-flex e-con e-child\" data-id=\"a687ab9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-647e910 elementor-widget elementor-widget-image\" data-id=\"647e910\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"609\" height=\"567\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Frame-350.webp\" class=\"attachment-large size-large wp-image-1629\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Frame-350.webp 609w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Frame-350-300x279.webp 300w\" sizes=\"(max-width: 609px) 100vw, 609px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ae118ce e-con-full e-flex e-con e-child\" data-id=\"ae118ce\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4cd58c8 elementor-widget elementor-widget-heading\" data-id=\"4cd58c8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Moderniser les syst\u00e8mes eLearning existants \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ec9f39 elementor-widget elementor-widget-heading\" data-id=\"2ec9f39\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Revitalisez votre syst\u00e8me eLearning obsol\u00e8te gr\u00e2ce \u00e0 nos services de modernisation :<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40e0ae4 elementor-widget elementor-widget-text-editor\" data-id=\"40e0ae4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>\u00c9valuation des besoins d&rsquo;apprentissage : \u00c9valuez vos besoins actuels en mati\u00e8re d&rsquo;apprentissage afin d&rsquo;orienter le processus de modernisation.<\/li><li>Am\u00e9lioration des processus : Red\u00e9finir et am\u00e9liorer les processus d&rsquo;apprentissage existants pour obtenir de meilleurs r\u00e9sultats.<\/li><li>Recommandations de nouvelles fonctionnalit\u00e9s : Sugg\u00e9rez des fonctionnalit\u00e9s innovantes telles que la gamification et les flux de travail de publication de cours.<\/li><li>Migration dans le nuage : Transf\u00e9rez votre plateforme eLearning vers le cloud pour am\u00e9liorer l&rsquo;accessibilit\u00e9 et l&rsquo;\u00e9volutivit\u00e9.<\/li><li>D\u00e9veloppement et test de fonctionnalit\u00e9s : Mettre en \u0153uvre et tester rigoureusement les nouvelles fonctionnalit\u00e9s.<\/li><li>Am\u00e9liorations UX\/UI : Am\u00e9liorez l&rsquo;interface utilisateur et l&rsquo;exp\u00e9rience globale de votre syst\u00e8me eLearning.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b349ebd e-con-full e-flex e-con e-child\" data-id=\"b349ebd\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-191702d e-con-full e-flex e-con e-child\" data-id=\"191702d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-11db8c5 elementor-widget elementor-widget-heading\" data-id=\"11db8c5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Personnalisez une plateforme eLearning Open-Source \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c330d2 elementor-widget elementor-widget-heading\" data-id=\"9c330d2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Adapter une plateforme eLearning open-source pour r\u00e9pondre \u00e0 vos besoins sp\u00e9cifiques :<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfe4408 elementor-widget elementor-widget-text-editor\" data-id=\"cfe4408\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Collecte des besoins : Comprendre et documenter vos besoins sp\u00e9cifiques en mati\u00e8re d&rsquo;apprentissage en ligne.  <\/li><li>Recommandation de plateforme : Conseils sur la plateforme open-source la mieux adapt\u00e9e \u00e0 vos besoins.  <br>Personnalisation de la plateforme : Adaptez la plateforme aux flux de travail et aux \u00e9valuations qui vous sont propres.  <\/li><li>Test de la solution : Testez minutieusement la plateforme personnalis\u00e9e pour vous assurer de sa fonctionnalit\u00e9.  <\/li><li>Formation des utilisateurs et assistance permanente : Fournissez la formation et l&rsquo;assistance n\u00e9cessaires pour maximiser l&rsquo;efficacit\u00e9 de la plateforme.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-547ae6f e-con-full e-flex e-con e-child\" data-id=\"547ae6f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21e9998 elementor-widget elementor-widget-image\" data-id=\"21e9998\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"609\" height=\"567\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Group-481751.webp\" class=\"attachment-large size-large wp-image-1630\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Group-481751.webp 609w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Group-481751-300x279.webp 300w\" sizes=\"(max-width: 609px) 100vw, 609px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-83bad28 e-con-full e-flex e-con e-parent\" data-id=\"83bad28\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a854eba e-flex e-con-boxed e-con e-child\" data-id=\"a854eba\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-81660f5 elementor-widget elementor-widget-heading\" data-id=\"81660f5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L'expertise technologique au service des solutions de nouvelle g\u00e9n\u00e9ration<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a3f8f50 e-con-full e-flex e-con e-child\" data-id=\"a3f8f50\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f98dd7f tab36 elementor-widget elementor-widget-ucaddon_content_tabs\" data-id=\"f98dd7f\" data-element_type=\"widget\" data-widget_type=\"ucaddon_content_tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Content Tabs -->\n\t\t<link id='font-awesome-css' href='https:\/\/integrass.ca\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/integrass.ca\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-v4-shims.min.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Content Tabs *\/\n\n#uc_content_tabs_elementor_f98dd7f \n{ \n  text-align: left; \n  position: relative;\n  overflow:hidden;\n  display:flex;\n  flex-direction:row;\n}\n\n\n#uc_content_tabs_elementor_f98dd7f .ue-graphic-element\n{\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  line-height:1em;\n  overflow:hidden;\n}\n\n#uc_content_tabs_elementor_f98dd7f .ue-graphic-element svg\n{\n  height:1em;\n  width:1em;\n}\n\n#uc_content_tabs_elementor_f98dd7f .ue-graphic-element img\n{\n  display:block;\n}\n\n#uc_content_tabs_elementor_f98dd7f .ue-item-image img\n{\n  width:100%;\n  display:block;\n}\n\n#uc_content_tabs_elementor_f98dd7f .uc_container .uc_btn {\n\n    text-align: center;\n    display: inline-block;\n    text-decoration: none;\n    transition: ease-in-out all 0.25s;\n}\n\n#uc_content_tabs_elementor_f98dd7f .uc_tab_nav{\n\tflex-direction:column;\n    flex-grow:0;\n    flex-shrink:0;\n}  \n\t\n\n\n#uc_content_tabs_elementor_f98dd7f * {\n    box-sizing: border-box;\n}\n#uc_content_tabs_elementor_f98dd7f .ue-tab-btn\n{\n  transition: 0.5s;\n} \n\n#uc_content_tabs_elementor_f98dd7f > ul.tabs{\n   margin:0px;\n   list-style:none;\n   display:flex;\n}\n\n\n  #uc_content_tabs_elementor_f98dd7f > ul.tabs{\n      justify-content:flex-start;\n      flex-wrap: wrap;\n  }\n\n\n#uc_content_tabs_elementor_f98dd7f > ul.tabs > li\n{\n\tpadding:0px; \n\tmargin:0px;\n    \t\n\n}\n\n\n\t\n#uc_content_tabs_elementor_f98dd7f > ul.tabs > li > a {\n\t\n\tdisplay:flex;\n\ttext-decoration:none;\n    transition:0.5s;\n    flex-wrap: wrap;\n    \n}\n\n#uc_content_tabs_elementor_f98dd7f .tab-container {\n\tclear:both;\n\toverflow:hidden;\n}\n\n#uc_content_tabs_elementor_f98dd7f .ue_post_image img\n{\n  display:block;\n  width:100%;\n  object-fit: cover;\n}\n\n#uc_content_tabs_elementor_f98dd7f .ue_post_link\n{\n  display:;\n  text-decoration:none;\n}\n\n#uc_content_tabs_elementor_f98dd7f .panes{ display:none;}\n#uc_content_tabs_elementor_f98dd7f.r-tabs .r-tabs-tab {\n    display: block;\n    margin: 0;\n    list-style: none;\n}\n\n#uc_content_tabs_elementor_f98dd7f.r-tabs .r-tabs-panel {\n    display: none;\n}\n\n#uc_content_tabs_elementor_f98dd7f.r-tabs .r-tabs-accordion-title {\n    display: none;\n}\n\n#uc_content_tabs_elementor_f98dd7f.r-tabs .r-tabs-panel.r-tabs-state-active {\n    display: flex;\n}\n#uc_content_tabs_elementor_f98dd7f .panel-container{\n   width:100%;\n }\n\n\n@media only screen and (max-width: 768px){\n  \n #uc_content_tabs_elementor_f98dd7f > ul.tabs {display:none;}\n #uc_content_tabs_elementor_f98dd7f.r-tabs .r-tabs-nav { display: none;}\n\n #uc_content_tabs_elementor_f98dd7f.r-tabs .r-tabs-accordion-title { display: block;}\n #uc_content_tabs_elementor_f98dd7f .r-tabs-accordion-title .r-tabs-anchor{ \n      display:flex;\n      align-items:center;\n      overflow:hidden; \n }\n  \n #uc_content_tabs_elementor_f98dd7f .uc-tabs-accordion-title{\n     flex-grow:1;\n }\n  \n #uc_content_tabs_elementor_f98dd7f .r-tabs-accordion-title .uc-accordion-icon-collapse{\n    display:none;    \n }\n  \n #uc_content_tabs_elementor_f98dd7f .r-tabs-accordion-title.r-tabs-state-active .uc-accordion-icon-collapse{\n    display:block;\n }\n  \n #uc_content_tabs_elementor_f98dd7f .r-tabs-accordion-title.r-tabs-state-active .uc-accordion-icon-expand{\n    display:none;\n }\n  \n #uc_content_tabs_elementor_f98dd7f .ue-item-content-layout{\n    display:flex;\n    flex-direction:column;\n }\n\n #uc_content_tabs_elementor_f98dd7f .ue-item-image-wrapper{\n \twidth:100%;\n }\n\n #uc_content_tabs_elementor_f98dd7f .uc-tabs-accordion-title{\n    display:flex;\n    align-items:center;\n }\n\n #uc_content_tabs_elementor_f98dd7f .panel-container{\n   width:100%;\n    } \n  \n  #uc_content_tabs_elementor_f98dd7f .tab-container{\n    background-color: ;\n  }\n  \n}\n\n\n\n\n\n\n\n\n\n\n\n<\/style>\n\n<div class=\"uc_bold_tabs padding  \" id=\"uc_content_tabs_elementor_f98dd7f\"  data-debug=\"false\" data-editor=\"no\"  data-collapsible=\"true\" data-hash=\"false\" data-hash-scroll=\"off\" data-scroll-to-selected-tab-offset=\"0\" data-scroll-after-selected=\"false\">\n    \t<ul class=\"tabs uc_tab_nav uc-items-wrapper\">\n        \t\n<li class=\"elementor-repeater-item-71db0cc\">\n  \t\n  \t<a href=\"javascript:void(0);\" data-content-id=\"uc_content_tabs_elementor_f98dd7f_item1\"  data-hash-id=\"ue-tab1\" class=\"ue-tab-btn\">\n \t              \t   \n      <div>Langages de programmation back-end<\/div>\n    <\/a>\n      \n<\/li>\n\n<li class=\"elementor-repeater-item-ba73ac5\">\n  \t\n  \t<a href=\"javascript:void(0);\" data-content-id=\"uc_content_tabs_elementor_f98dd7f_item2\"  data-hash-id=\"ue-tab2\" class=\"ue-tab-btn\">\n \t              \t   \n      <div>Langages de programmation frontaux<\/div>\n    <\/a>\n      \n<\/li>\n\n<li class=\"elementor-repeater-item-2f0315f\">\n  \t\n  \t<a href=\"javascript:void(0);\" data-content-id=\"uc_content_tabs_elementor_f98dd7f_item3\"  data-hash-id=\"ue-tab3\" class=\"ue-tab-btn\">\n \t              \t   \n      <div>Mobile<\/div>\n    <\/a>\n      \n<\/li>\n\n<li class=\"elementor-repeater-item-1b1b27a\">\n  \t\n  \t<a href=\"javascript:void(0);\" data-content-id=\"uc_content_tabs_elementor_f98dd7f_item4\"  data-hash-id=\"ue-tab4\" class=\"ue-tab-btn\">\n \t              \t   \n      <div>Expertise de la plate-forme<\/div>\n    <\/a>\n      \n<\/li>\n\n<li class=\"elementor-repeater-item-9d4a4c0\">\n  \t\n  \t<a href=\"javascript:void(0);\" data-content-id=\"uc_content_tabs_elementor_f98dd7f_item5\"  data-hash-id=\"ue-tab5\" class=\"ue-tab-btn\">\n \t              \t   \n      <div>Bases de donn\u00e9es \/ Stockages de donn\u00e9es<\/div>\n    <\/a>\n      \n<\/li>\n\n<li class=\"elementor-repeater-item-6eaaa97\">\n  \t\n  \t<a href=\"javascript:void(0);\" data-content-id=\"uc_content_tabs_elementor_f98dd7f_item6\"  data-hash-id=\"ue-tab6\" class=\"ue-tab-btn\">\n \t              \t   \n      <div>Bases de donn\u00e9es, entrep\u00f4ts et stockage en nuage<\/div>\n    <\/a>\n      \n<\/li>\n\n<li class=\"elementor-repeater-item-3bfefa7\">\n  \t\n  \t<a href=\"javascript:void(0);\" data-content-id=\"uc_content_tabs_elementor_f98dd7f_item7\"  data-hash-id=\"ue-tab7\" class=\"ue-tab-btn\">\n \t              \t   \n      <div>Services en nuage<\/div>\n    <\/a>\n      \n<\/li>\n\n<li class=\"elementor-repeater-item-21421d9\">\n  \t\n  \t<a href=\"javascript:void(0);\" data-content-id=\"uc_content_tabs_elementor_f98dd7f_item8\"  data-hash-id=\"ue-tab8\" class=\"ue-tab-btn\">\n \t              \t   \n      <div>Plates-formes d'IA<\/div>\n    <\/a>\n      \n<\/li>\n\n        <\/ul>\n        <div class=\"panel-container uc-items-wrapper2\">\n\t\t\t<div id=\"uc_content_tabs_elementor_f98dd7f_item1\" class=\"tab-container panes\">\n\t<div>\n      \t\t<div data-elementor-type=\"section\" data-elementor-id=\"20904\" class=\"elementor elementor-20904 elementor-3056\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-380cccf e-flex e-con-boxed e-con e-parent\" data-id=\"380cccf\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a8ca191 e-con-full e-flex e-con e-child\" data-id=\"a8ca191\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e65340e elementor-widget elementor-widget-heading\" data-id=\"e65340e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Langages de programmation back-end\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cae4e90 e-con-full e-flex e-con e-child\" data-id=\"cae4e90\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8bbdcb4 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"8bbdcb4\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-20984 gallery-columns-7 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/0-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/0-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/0-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/0.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/1-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/1-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/1-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/1.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/2-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/2-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/2-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/2.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/3-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/3-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/3-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/3.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/4-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/4-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/4-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/4.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/5-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/5-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/5-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/5.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/6-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/6-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/6-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/6.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            \n      \t<\/div>\n<\/div>\n<div id=\"uc_content_tabs_elementor_f98dd7f_item2\" class=\"tab-container panes\">\n\t<div>\n      \t\t<div data-elementor-type=\"section\" data-elementor-id=\"20900\" class=\"elementor elementor-20900 elementor-3059\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-adc3bff e-flex e-con-boxed e-con e-parent\" data-id=\"adc3bff\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-899fba6 e-con-full e-flex e-con e-child\" data-id=\"899fba6\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cba0c1d elementor-widget elementor-widget-heading\" data-id=\"cba0c1d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Langues\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d9966f3 e-con-full e-flex e-con e-child\" data-id=\"d9966f3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-436c78a gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"436c78a\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-20563 gallery-columns-5 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/7-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/7-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/7-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/7.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/8-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/8-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/8-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/8.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/9-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/9-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/9-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/9.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74fc56b elementor-widget elementor-widget-heading\" data-id=\"74fc56b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cadres JavaScript\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f5e01fe e-con-full e-flex e-con e-child\" data-id=\"f5e01fe\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-259b7b4 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"259b7b4\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-2' class='gallery galleryid-20563 gallery-columns-7 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/10-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/10-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/10-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/10.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/11-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/11-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/11-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/11.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/12-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/12-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/12-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/12.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/131-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/131-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/131-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/131.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-94-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-94-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-94-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-94.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/132-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/132-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/132-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/132.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            \n      \t<\/div>\n<\/div>\n<div id=\"uc_content_tabs_elementor_f98dd7f_item3\" class=\"tab-container panes\">\n\t<div>\n      \t\t<div data-elementor-type=\"section\" data-elementor-id=\"20858\" class=\"elementor elementor-20858 elementor-3261\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-faa46aa e-flex e-con-boxed e-con e-parent\" data-id=\"faa46aa\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f19873b e-con-full e-flex e-con e-child\" data-id=\"f19873b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23d7225 elementor-widget elementor-widget-heading\" data-id=\"23d7225\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mobile\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-76ff854 e-con-full e-flex e-con e-child\" data-id=\"76ff854\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57a35a0 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"57a35a0\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-20984 gallery-columns-7 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/133-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/133-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/133-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/133.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/134-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/134-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/134-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/134.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/135-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/135-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/135-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/135.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/136-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/136-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/136-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/136.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/137-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/137-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/137-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/137.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/138-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/138-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/138-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/138.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/139-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/139-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/139-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/139.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-102-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-102-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-102-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-102.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            \n      \t<\/div>\n<\/div>\n<div id=\"uc_content_tabs_elementor_f98dd7f_item4\" class=\"tab-container panes\">\n\t<div>\n      \t\t<div data-elementor-type=\"section\" data-elementor-id=\"20835\" class=\"elementor elementor-20835 elementor-3323\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-39b04f6 e-flex e-con-boxed e-con e-parent\" data-id=\"39b04f6\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d53d92a e-con-full e-flex e-con e-child\" data-id=\"d53d92a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f7f0443 elementor-widget elementor-widget-heading\" data-id=\"f7f0443\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Expertise de la plate-forme\n\n\n\n\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f9d855b e-con-full e-flex e-con e-child\" data-id=\"f9d855b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aacbcb4 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"aacbcb4\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-2' class='gallery galleryid-20984 gallery-columns-7 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/148-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/148-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/148-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/148.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-274-1-150x150.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-274-1-150x150.webp 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-274-1-300x300.webp 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-274-1.webp 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-213-2-150x150.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-213-2-150x150.webp 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-213-2-300x300.webp 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-213-2.webp 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-207-1-150x150.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-207-1-150x150.webp 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-207-1-300x300.webp 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-207-1.webp 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-208-1-150x150.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-208-1-150x150.webp 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-208-1-300x300.webp 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-208-1.webp 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-272-1-150x150.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-272-1-150x150.webp 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-272-1-300x300.webp 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-272-1.webp 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-210-2-150x150.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-210-2-150x150.webp 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-210-2-300x300.webp 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-210-2.webp 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-211-2-150x150.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-211-2-150x150.webp 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-211-2-300x300.webp 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-211-2.webp 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-212-2-150x150.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-212-2-150x150.webp 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-212-2-300x300.webp 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-212-2.webp 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            \n      \t<\/div>\n<\/div>\n<div id=\"uc_content_tabs_elementor_f98dd7f_item5\" class=\"tab-container panes\">\n\t<div>\n      \t\t<div data-elementor-type=\"section\" data-elementor-id=\"20888\" class=\"elementor elementor-20888 elementor-3071\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-edeb3eb e-flex e-con-boxed e-con e-parent\" data-id=\"edeb3eb\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e730bae e-con-full e-flex e-con e-child\" data-id=\"e730bae\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ba9e536 elementor-widget elementor-widget-heading\" data-id=\"ba9e536\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SQL\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-31e000d e-con-full e-flex e-con e-child\" data-id=\"31e000d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9a6e86c gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"9a6e86c\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-20596 gallery-columns-7 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/40-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/40-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/40-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/40.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/41-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/41-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/41-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/41.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/45-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/45-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/45-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/45.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/42-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/42-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/42-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/42.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/43-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/43-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/43-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/43.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cb5efc elementor-widget elementor-widget-heading\" data-id=\"6cb5efc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">NoSQL<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-83ad9ce e-con-full e-flex e-con e-child\" data-id=\"83ad9ce\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-10721df gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"10721df\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-2' class='gallery galleryid-20596 gallery-columns-7 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/51-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/51-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/51-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/51.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/53-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/53-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/53-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/53.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/55-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/55-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/55-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/55.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-118-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-118-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-118-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-118.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-119-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-119-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-119-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-119.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            \n      \t<\/div>\n<\/div>\n<div id=\"uc_content_tabs_elementor_f98dd7f_item6\" class=\"tab-container panes\">\n\t<div>\n      \t\t<div data-elementor-type=\"section\" data-elementor-id=\"20884\" class=\"elementor elementor-20884 elementor-3079\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-764d323 e-flex e-con-boxed e-con e-parent\" data-id=\"764d323\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2d1e12e e-con-full e-flex e-con e-child\" data-id=\"2d1e12e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a959e4 elementor-widget elementor-widget-heading\" data-id=\"7a959e4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">AWS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9ded9d9 e-con-full e-flex e-con e-child\" data-id=\"9ded9d9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f804379 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"f804379\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-3' class='gallery galleryid-20596 gallery-columns-7 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/47-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/47-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/47-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/47.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/59-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/59-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/59-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/59.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/60-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/60-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/60-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/60.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/61-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/61-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/61-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/61.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/46-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/46-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/46-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/46.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/62-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/62-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/62-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/62.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f18535b elementor-widget elementor-widget-heading\" data-id=\"f18535b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L'azur<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ddab83a e-con-full e-flex e-con e-child\" data-id=\"ddab83a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1004a67 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"1004a67\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-4' class='gallery galleryid-20596 gallery-columns-7 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/58-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/58-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/58-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/58.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/57-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/57-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/57-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/57.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/56-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/56-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/56-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/56.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/45-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/45-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/45-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/45.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-127-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-127-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-127-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-127.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-125-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-125-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-125-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-125.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-126-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-126-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-126-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/10\/logo-126.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c0f7541 e-con-full e-flex e-con e-child\" data-id=\"c0f7541\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4cbfab3 elementor-widget elementor-widget-heading\" data-id=\"4cbfab3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Google Cloud Platform\n\n\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b47af2 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"1b47af2\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-5' class='gallery galleryid-20596 gallery-columns-7 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/64-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/64-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/64-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/64.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/48-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/48-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/48-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/48.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            \n      \t<\/div>\n<\/div>\n<div id=\"uc_content_tabs_elementor_f98dd7f_item7\" class=\"tab-container panes\">\n\t<div>\n      \t\t<div data-elementor-type=\"section\" data-elementor-id=\"20832\" class=\"elementor elementor-20832 elementor-3324\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-3ee2353 e-flex e-con-boxed e-con e-parent\" data-id=\"3ee2353\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bd67362 e-con-full e-flex e-con e-child\" data-id=\"bd67362\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-88b00c1 elementor-widget elementor-widget-heading\" data-id=\"88b00c1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Services en nuage\n\n\n\n\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-be1c891 e-con-full e-flex e-con e-child\" data-id=\"be1c891\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e5cb65 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"1e5cb65\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-3' class='gallery galleryid-20984 gallery-columns-5 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/35-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/35-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/35-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/35.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/36-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/36-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/36-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/36.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/37-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/37-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/37-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/37.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            \n      \t<\/div>\n<\/div>\n<div id=\"uc_content_tabs_elementor_f98dd7f_item8\" class=\"tab-container panes\">\n\t<div>\n      \t\t<div data-elementor-type=\"section\" data-elementor-id=\"20848\" class=\"elementor elementor-20848 elementor-3333\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-6d3b8ae e-flex e-con-boxed e-con e-parent\" data-id=\"6d3b8ae\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-548cd57 e-con-full e-flex e-con e-child\" data-id=\"548cd57\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-43653af elementor-widget elementor-widget-heading\" data-id=\"43653af\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Plates-formes d'IA\n\n\n\n\n\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9daee11 e-con-full e-flex e-con e-child\" data-id=\"9daee11\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-82ef3cb gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"82ef3cb\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-4' class='gallery galleryid-20984 gallery-columns-5 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/81-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/81-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/81-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/81.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/71-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/71-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/71-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/71.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/82-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/82-150x150.png 150w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/82-300x300.png 300w, https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/82.png 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            \n      \t<\/div>\n<\/div>\n\n        <\/div>\n  \n  <div class=\"uc-accordion-contents-template\" style=\"display:none\">\n    <div class=\"uc-accordion-icon\">\n      <span class=\"uc-accordion-icon-expand\"><i class='fas fa-plus'><\/i><\/span>\n      <span class=\"uc-accordion-icon-collapse\"><i class='fas fa-minus'><\/i><\/span>\n    <\/div>\n  <\/div>\n  \n<\/div>\n<!-- end Content Tabs -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ed8a72 e-con-full e-flex e-con e-parent\" data-id=\"3ed8a72\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4e73b7b e-flex e-con-boxed e-con e-child\" data-id=\"4e73b7b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9d7825d elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"9d7825d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pourquoi choisir le d\u00e9veloppement de logiciels eLearning ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb74067 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"fb74067\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLa mise en \u0153uvre d&rsquo;une solution eLearning\nd\u00e9velopp\u00e9e par des professionnels offre de nombreux avantages.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5918591 e-con-full e-flex e-con e-child\" data-id=\"5918591\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f2b3406 e-con-full e-flex e-con e-child\" data-id=\"f2b3406\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-df343ce elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"df343ce\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"121\" height=\"120\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Frame-008.webp\" class=\"attachment-full size-full wp-image-1324\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Un retour sur investissement significatif<\/h3><p class=\"elementor-image-box-description\">Obtenez un retour sur investissement annuel de 220 \u00e0 650 % gr\u00e2ce \u00e0 un rapport optimal entre le co\u00fbt et la valeur des fonctionnalit\u00e9s et \u00e0 l'utilisation de technologies de pointe.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3da84ba e-con-full e-flex e-con e-child\" data-id=\"3da84ba\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bcb5ecd elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"bcb5ecd\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"121\" height=\"120\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Frame-008.webp\" class=\"attachment-full size-full wp-image-1324\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">R\u00e9duction des co\u00fbts d'apprentissage<\/h3><p class=\"elementor-image-box-description\">R\u00e9duire les d\u00e9penses d'apprentissage de 25 \u00e0 75 % en \u00e9conomisant sur le mat\u00e9riel, l'\u00e9quipement et le personnel.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c691ab5 e-con-full e-flex e-con e-child\" data-id=\"c691ab5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eac5a5f elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"eac5a5f\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"121\" height=\"120\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Frame-008.webp\" class=\"attachment-full size-full wp-image-1324\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Augmentation de la productivit\u00e9<\/h3><p class=\"elementor-image-box-description\">Augmentez la productivit\u00e9 de vos employ\u00e9s de 35 \u00e0 80 % gr\u00e2ce \u00e0 l'am\u00e9lioration de leurs comp\u00e9tences, \u00e0 la sensibilisation aux politiques et \u00e0 l'acc\u00e8s \u00e0 l'apprentissage \u00e0 la demande.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-20baf97 e-con-full e-flex e-con e-child\" data-id=\"20baf97\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cd39d7d elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"cd39d7d\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"121\" height=\"120\" src=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Frame-008.webp\" class=\"attachment-full size-full wp-image-1324\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Am\u00e9lioration de la r\u00e9tention des connaissances<\/h3><p class=\"elementor-image-box-description\">Am\u00e9liorez la r\u00e9tention des connaissances de 30 \u00e0 50 % gr\u00e2ce \u00e0 un contenu eLearning vari\u00e9 et \u00e0 des exp\u00e9riences d'apprentissage percutantes.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d5ce65f e-con-full e-flex e-con e-parent\" data-id=\"d5ce65f\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8211798 e-flex e-con-boxed e-con e-child\" data-id=\"8211798\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bf418fd e-con-full e-flex e-con e-child\" data-id=\"bf418fd\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-b53a6d1 e-con-full e-flex e-con e-child\" data-id=\"b53a6d1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c976a38 elementor-widget elementor-widget-heading\" data-id=\"c976a38\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Permettez \u00e0 nos d\u00e9veloppeurs de vous aider \u00e0 obtenir ces avantages !<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-956205d elementor-widget elementor-widget-text-editor\" data-id=\"956205d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tContactez l&rsquo;\u00e9quipe d&rsquo;Integrass d\u00e8s aujourd&rsquo;hui pour faire progresser vos initiatives d&rsquo;apprentissage en entreprise gr\u00e2ce \u00e0 des solutions technologiques de pointe.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d41b671 e-con-full e-flex e-con e-child\" data-id=\"d41b671\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-74caa66 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"74caa66\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/integrass.ca\/fr\/consultation\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Services de d\u00e9veloppement de logiciels eLearning et de LMS Depuis 2011, Integrass est \u00e0 l&rsquo;avant-garde du d\u00e9veloppement de solutions eLearning qui am\u00e9liorent l&rsquo;apprentissage en entreprise et offrent des retours mesurables sur le capital humain. Notre \u00e9quipe est \u00e9quip\u00e9e pour \u00e9lever votre apprentissage d&rsquo;entreprise avec une technologie innovante ou pour mettre \u00e0 jour vos syst\u00e8mes eLearning [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"iawp_total_views":11,"footnotes":""},"class_list":["post-20984","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.7 (Yoast SEO v26.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>D\u00e9veloppement de logiciels eLearning personnalis\u00e9s<\/title>\n<meta name=\"description\" content=\"Cr\u00e9ez des solutions eLearning innovantes gr\u00e2ce \u00e0 nos services de d\u00e9veloppement. Faites confiance aux plateformes LMS et \u00e9ducatives.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/integrass.ca\/fr\/apprentissage-en-ligne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apprentissage en ligne\" \/>\n<meta property=\"og:description\" content=\"As a leader in software development with over 13+ years of experience, we create robust, scalable, and secure software for any OS, browser, or device.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/integrass.ca\/fr\/apprentissage-en-ligne\/\" \/>\n<meta property=\"og:site_name\" content=\"Integrass\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IntegrassGlobalCompany\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-26T08:44:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Group-4-10.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"548\" \/>\n\t<meta property=\"og:image:height\" content=\"651\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@IntegrassGlobal\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"44 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/integrass.ca\/fr\/apprentissage-en-ligne\/\",\"url\":\"https:\/\/integrass.ca\/fr\/apprentissage-en-ligne\/\",\"name\":\"D\u00e9veloppement de logiciels eLearning personnalis\u00e9s\",\"isPartOf\":{\"@id\":\"https:\/\/integrass.ca\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/integrass.ca\/fr\/apprentissage-en-ligne\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/integrass.ca\/fr\/apprentissage-en-ligne\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Group-4-10.webp\",\"datePublished\":\"2024-09-13T15:03:31+00:00\",\"dateModified\":\"2025-02-26T08:44:30+00:00\",\"description\":\"Cr\u00e9ez des solutions eLearning innovantes gr\u00e2ce \u00e0 nos services de d\u00e9veloppement. Faites confiance aux plateformes LMS et \u00e9ducatives.\",\"breadcrumb\":{\"@id\":\"https:\/\/integrass.ca\/fr\/apprentissage-en-ligne\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/integrass.ca\/fr\/apprentissage-en-ligne\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/integrass.ca\/fr\/apprentissage-en-ligne\/#primaryimage\",\"url\":\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Group-4-10.webp\",\"contentUrl\":\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Group-4-10.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/integrass.ca\/fr\/apprentissage-en-ligne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/integrass.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apprentissage en ligne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/integrass.ca\/fr\/#website\",\"url\":\"https:\/\/integrass.ca\/fr\/\",\"name\":\"Integrass\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/integrass.ca\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/integrass.ca\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/integrass.ca\/fr\/#organization\",\"name\":\"Integrass\",\"url\":\"https:\/\/integrass.ca\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/integrass.ca\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/12\/Integrass-logo-2.png\",\"contentUrl\":\"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/12\/Integrass-logo-2.png\",\"width\":512,\"height\":512,\"caption\":\"Integrass\"},\"image\":{\"@id\":\"https:\/\/integrass.ca\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/IntegrassGlobalCompany\/\",\"https:\/\/x.com\/IntegrassGlobal\",\"https:\/\/www.linkedin.com\/company\/integrass-global\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"D\u00e9veloppement de logiciels eLearning personnalis\u00e9s","description":"Cr\u00e9ez des solutions eLearning innovantes gr\u00e2ce \u00e0 nos services de d\u00e9veloppement. Faites confiance aux plateformes LMS et \u00e9ducatives.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/integrass.ca\/fr\/apprentissage-en-ligne\/","og_locale":"fr_FR","og_type":"article","og_title":"Apprentissage en ligne","og_description":"As a leader in software development with over 13+ years of experience, we create robust, scalable, and secure software for any OS, browser, or device.","og_url":"https:\/\/integrass.ca\/fr\/apprentissage-en-ligne\/","og_site_name":"Integrass","article_publisher":"https:\/\/www.facebook.com\/IntegrassGlobalCompany\/","article_modified_time":"2025-02-26T08:44:30+00:00","og_image":[{"width":548,"height":651,"url":"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Group-4-10.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@IntegrassGlobal","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"44 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/integrass.ca\/fr\/apprentissage-en-ligne\/","url":"https:\/\/integrass.ca\/fr\/apprentissage-en-ligne\/","name":"D\u00e9veloppement de logiciels eLearning personnalis\u00e9s","isPartOf":{"@id":"https:\/\/integrass.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/integrass.ca\/fr\/apprentissage-en-ligne\/#primaryimage"},"image":{"@id":"https:\/\/integrass.ca\/fr\/apprentissage-en-ligne\/#primaryimage"},"thumbnailUrl":"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Group-4-10.webp","datePublished":"2024-09-13T15:03:31+00:00","dateModified":"2025-02-26T08:44:30+00:00","description":"Cr\u00e9ez des solutions eLearning innovantes gr\u00e2ce \u00e0 nos services de d\u00e9veloppement. Faites confiance aux plateformes LMS et \u00e9ducatives.","breadcrumb":{"@id":"https:\/\/integrass.ca\/fr\/apprentissage-en-ligne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/integrass.ca\/fr\/apprentissage-en-ligne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/integrass.ca\/fr\/apprentissage-en-ligne\/#primaryimage","url":"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Group-4-10.webp","contentUrl":"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/09\/Group-4-10.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/integrass.ca\/fr\/apprentissage-en-ligne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/integrass.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Apprentissage en ligne"}]},{"@type":"WebSite","@id":"https:\/\/integrass.ca\/fr\/#website","url":"https:\/\/integrass.ca\/fr\/","name":"Integrass","description":"","publisher":{"@id":"https:\/\/integrass.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/integrass.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/integrass.ca\/fr\/#organization","name":"Integrass","url":"https:\/\/integrass.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/integrass.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/12\/Integrass-logo-2.png","contentUrl":"https:\/\/integrass.ca\/wp-content\/uploads\/2024\/12\/Integrass-logo-2.png","width":512,"height":512,"caption":"Integrass"},"image":{"@id":"https:\/\/integrass.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IntegrassGlobalCompany\/","https:\/\/x.com\/IntegrassGlobal","https:\/\/www.linkedin.com\/company\/integrass-global"]}]}},"_links":{"self":[{"href":"https:\/\/integrass.ca\/fr\/wp-json\/wp\/v2\/pages\/20984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/integrass.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/integrass.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/integrass.ca\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/integrass.ca\/fr\/wp-json\/wp\/v2\/comments?post=20984"}],"version-history":[{"count":0,"href":"https:\/\/integrass.ca\/fr\/wp-json\/wp\/v2\/pages\/20984\/revisions"}],"wp:attachment":[{"href":"https:\/\/integrass.ca\/fr\/wp-json\/wp\/v2\/media?parent=20984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}